{"id":572,"date":"2012-03-24T10:12:00","date_gmt":"2012-03-24T09:12:00","guid":{"rendered":"http:\/\/blog.xaranx.de\/?p=572"},"modified":"2012-12-31T19:16:14","modified_gmt":"2012-12-31T18:16:14","slug":"t-mobile-sim-lock-sperre-entfernen","status":"publish","type":"post","link":"http:\/\/blog.xaranx.de\/index.php\/2012\/03\/t-mobile-sim-lock-sperre-entfernen","title":{"rendered":"T-Mobile SIM-Lock Sperre entfernen"},"content":{"rendered":"<p><em>&#8222;<strong>SIM-Lock Ihres Handys entsperren<\/strong>1)<\/em><\/p>\n<p><em>Wenn Sie Ihr Handy mit der Mobilfunk-Karte eines anderen Anbieters nutzen wollen, m\u00fcssen Sie zun\u00e4chst den SIM-Lock entfernen. Den Entsperrcode k\u00f6nnen Sie 24 Monate nach dem Kauf kostenlos erhalten. Wenn Sie Ihr Handy vor Ablauf der 24 Monate entsperren m\u00f6chten, k\u00f6nnen Sie den Entsperrcode online f\u00fcr 99,50 \u20ac2) bestellen. Eine vorzeitige Entsperrung eines iPhones ist nicht m\u00f6glich.<\/em><\/p>\n<p><em>1) Sie haben maximal 10 Versuche, um Ihr Handy zu entsperren. Danach k\u00f6nnen Sie das Mobiltelefon nicht mehr f\u00fcr andere Mobilfunk-Karten freischalten. \u00bbR-107\u00bb<\/em><br \/>\n<em> 2) Die Zustellung des Entsperrcodes erfolgt per Nachnahmesendung auf dem Postweg. \u00bbR-108\u00bb&#8220;<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211;&gt; <a href=\"http:\/\/www.t-mobile.de\/sim-lock-entsperren\/0,20638,23789-_,00.html\">SIM-Lock entsperren | Telekom<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;SIM-Lock Ihres Handys entsperren1) Wenn Sie Ihr Handy mit der Mobilfunk-Karte eines anderen Anbieters nutzen wollen, m\u00fcssen Sie zun\u00e4chst den SIM-Lock entfernen. Den Entsperrcode k\u00f6nnen Sie 24 Monate nach dem Kauf kostenlos erhalten. Wenn Sie Ihr Handy vor Ablauf der &hellip; <a href=\"http:\/\/blog.xaranx.de\/index.php\/2012\/03\/t-mobile-sim-lock-sperre-entfernen\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,18],"tags":[],"class_list":["post-572","post","type-post","status-publish","format-standard","hentry","category-internet","category-iphone"],"_links":{"self":[{"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/posts\/572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/comments?post=572"}],"version-history":[{"count":4,"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/posts\/572\/revisions"}],"predecessor-version":[{"id":602,"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/posts\/572\/revisions\/602"}],"wp:attachment":[{"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/media?parent=572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/categories?post=572"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blog.xaranx.de\/index.php\/wp-json\/wp\/v2\/tags?post=572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}